{"id":22039,"date":"2025-07-19T20:55:43","date_gmt":"2025-07-19T18:55:43","guid":{"rendered":"https:\/\/germainpatrons.com\/?post_type=product&#038;p=22039"},"modified":"2026-08-17T07:53:05","modified_gmt":"2026-08-17T05:53:05","slug":"celestine","status":"publish","type":"product","link":"https:\/\/germainpatrons.com\/en\/celestine\/","title":{"rendered":"C\u00e9lestine"},"content":{"rendered":"<p style=\"font-weight: 400;\">C\u00e9lestine, c\u2019est la veste cool, pratique et styl\u00e9e qui donne enfin envie de sortir en jogging\u2026 m\u00eame sans courir.<\/p>\n<p style=\"font-weight: 400;\">Pens\u00e9e comme une veste de jogging casual chic, C\u00e9lestine s\u2019adapte \u00e0 toutes vos envies, \u00e0 porter seule ou en total look avec le pantalon Ernest, pour un ensemble aussi douillet que styl\u00e9.<\/p>\n<p style=\"font-weight: 400;\">C\u00e9lestine, c\u2019est une veste avec une fermeture zipp\u00e9e sur le devant pour un enfilage facile, une capuche au choix (avec ou sans, selon l\u2019humeur)<\/p>\n<p style=\"font-weight: 400;\">Des poches plaqu\u00e9es \u00e0 rabat sur la poitrine pour un petit clin d\u2019\u0153il utilitaire, une coulisse \u00e0 la taille \u00e0 ajuster selon l\u2019envie (version loose ou cintr\u00e9e), deux longueurs au choix : courte et dynamique, ou plus longue pour un effet veste l\u00e9g\u00e8re.<\/p>\n<p style=\"font-weight: 400;\">\u00c0 coudre dans un jersey souple, un molleton, un interlock ou un Milano.<\/p>\n<p style=\"font-weight: 400;\">C\u00e9lestine sera votre alli\u00e9 du quotidien comme de vos moments cocooning.<\/p>\n<p style=\"font-weight: 400;\">[et_pb_section global_module=\"22761\"][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"font-weight: 400;\">C\u00e9lestine, c\u2019est la veste cool, pratique et styl\u00e9e qui donne enfin envie de sortir en jogging\u2026 m\u00eame sans courir.<\/p>\n<div class=\"dftail\"><em>Tailles : 34 au 48 \/ 46 au 60.<\/em><\/div>\n<div class=\"dficon\">\n<p><em>Niveau de difficult\u00e9 : <\/em><\/p>\n<div class=\"difficulty\"><\/div>\n<div class=\"difficulty\"><\/div>\n<\/div>\n<p>\u00c0 retrouver sur vos r\u00e9seaux : <a href=\"https:\/\/www.instagram.com\/explore\/tags\/vesteoxford\/?hl=fr\" target=\"_blank\" rel=\"noopener\">#vestecelestine<\/a>; <a href=\"https:\/\/www.instagram.com\/explore\/tags\/germainpatronsoxford\/?hl=fr\" target=\"_blank\" rel=\"noopener\">#germainpatronscelestine<\/a> ; <a href=\"https:\/\/www.instagram.com\/explore\/tags\/germainpatrons\/?hl=fr\" target=\"_blank\" rel=\"noopener\">#germainpatrons<\/a><\/p>\n","protected":false},"featured_media":23098,"template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<p style=\"font-weight: 400\">C\u00e9lestine, c\u2019est la veste cool, pratique et styl\u00e9e qui donne enfin envie de sortir en jogging\u2026 m\u00eame sans courir.<\/p>\r\n<p style=\"font-weight: 400\">Pens\u00e9e comme une veste de jogging casual chic, C\u00e9lestine s\u2019adapte \u00e0 toutes vos envies, \u00e0 porter seule ou en total look avec le pantalon Ernest, pour un ensemble aussi douillet que styl\u00e9.<\/p>\r\n<p style=\"font-weight: 400\">C\u00e9lestine, c\u2019est une veste avec une fermeture zipp\u00e9e sur le devant pour un enfilage facile, une capuche au choix (avec ou sans, selon l\u2019humeur)<\/p>\r\n<p style=\"font-weight: 400\">Des poches plaqu\u00e9es \u00e0 rabat sur la poitrine pour un petit clin d\u2019\u0153il utilitaire, une coulisse \u00e0 la taille \u00e0 ajuster selon l\u2019envie (version loose ou cintr\u00e9e), deux longueurs au choix : courte et dynamique, ou plus longue pour un effet veste l\u00e9g\u00e8re.<\/p>\r\n<p style=\"font-weight: 400\">\u00c0 coudre dans un jersey souple, un molleton, un interlock ou un Milano.<\/p>\r\n<p style=\"font-weight: 400\">C\u00e9lestine sera votre alli\u00e9 du quotidien comme de vos moments cocooning.<\/p>\r\n<p style=\"font-weight: 400\">[divi_shortcode id=\"22761\"]<\/p>","_et_gb_content_width":""},"product_brand":[],"product_cat":[73,67,36,37,63,71],"product_tag":[187,157],"class_list":["post-22039","product","type-product","status-publish","has-post-thumbnail","product_cat-manteaux-et-vestes-46-60-fr","product_cat-manteaux-et-vestes-34-48-fr","product_cat-patrons-de-couture-femmes-34-48-fr","product_cat-patrons-de-couture-femmes-46-60-fr","product_cat-sportswear-34-48-fr","product_cat-sportswear-46-60-fr","product_tag-187","product_tag-veste","pa_formats-pdf-34-48-fr","pa_formats-pdf-46-60-fr","pa_formats-pochette-34-48-fr","pa_formats-pochette-46-60-fr","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/germainpatrons.com\/en\/wp-json\/wp\/v2\/product\/22039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/germainpatrons.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/germainpatrons.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/germainpatrons.com\/en\/wp-json\/wp\/v2\/media\/23098"}],"wp:attachment":[{"href":"https:\/\/germainpatrons.com\/en\/wp-json\/wp\/v2\/media?parent=22039"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/germainpatrons.com\/en\/wp-json\/wp\/v2\/product_brand?post=22039"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/germainpatrons.com\/en\/wp-json\/wp\/v2\/product_cat?post=22039"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/germainpatrons.com\/en\/wp-json\/wp\/v2\/product_tag?post=22039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}